{"id":2427,"date":"2023-12-12T00:00:00","date_gmt":"2023-12-12T05:00:00","guid":{"rendered":"https:\/\/vinyform.com\/product\/bas-de-laine-a-30\/"},"modified":"2026-08-23T14:20:14","modified_gmt":"2026-08-23T18:20:14","slug":"bas-de-laine-a-30","status":"publish","type":"product","link":"https:\/\/vinyform.com\/fr\/produit\/bas-de-laine-a-30\/","title":{"rendered":"Bas de laine \u00e0 30%"},"content":{"rendered":"<p>Les bas de laine \u00e0 30% sont tr\u00e8s confortables. Ils sont doux et ont une semelle coussin\u00e9e. Le dessus des orteils est fait d\u2019un motif de tricot diff\u00e9rent qui permet \u00e0 l\u2019air de circuler et donc de r\u00e9duire la transpiration. Personnalisez ces bas en choisissant une couleur et avec un logo brod\u00e9 de 4 cm par 4 cm (jusqu\u2019\u00e0 4 couleurs de fils). (inclus dans le prix)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les bas de laine \u00e0 30% sont tr\u00e8s confortables. Ils sont doux et ont une semelle coussin\u00e9e. Le dessus des orteils est fait d&rsquo;un motif de tricot diff\u00e9rent qui permet \u00e0 l&rsquo;air de circuler et donc de r\u00e9duire la transpiration. Personnalisez ces bas en choisissant une couleur et avec un logo brod\u00e9 de 4 cm <\/p>\n","protected":false},"featured_media":493,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"industries":[121,47],"product_brand":[],"product_cat":[108,97],"product_tag":[],"class_list":["post-2427","product","type-product","status-publish","has-post-thumbnail","industries-articles-promotionnels","industries-promotionals-items","product_cat-bas","product_cat-items-promotionnels","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product\/2427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/comments?post=2427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/media\/493"}],"wp:attachment":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/media?parent=2427"}],"wp:term":[{"taxonomy":"industries","embeddable":true,"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/industries?post=2427"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product_brand?post=2427"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product_cat?post=2427"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product_tag?post=2427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}