{"id":140,"count":12,"description":"Autocollants d\u00e9coup\u00e9s au contour, graphiques de plancher, chevalets, autocollants pour fen\u00eatre et pour v\u00e9hicule, imprim\u00e9s en tons directs ou en quadrichromie sur des vinyles et des polyesters de qualit\u00e9 commerciale. Chaque pi\u00e8ce est fabriqu\u00e9e sur mesure d'apr\u00e8s votre visuel, avec le mat\u00e9riau et l'adh\u00e9sif adapt\u00e9s \u00e0 la surface \u2014 de la vitrine au hayon de camion.","link":"https:\/\/vinyform.com\/fr\/categorie-produit\/enseignes-et-autocollants\/","name":"Enseignes et autocollants","slug":"enseignes-et-autocollants","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product_cat\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/vinyform.com\/fr\/wp-json\/wp\/v2\/product?product_cat=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}